{"id":2959,"date":"2021-04-30T09:26:00","date_gmt":"2021-04-30T09:26:00","guid":{"rendered":"https:\/\/mobitrainee.com\/?p=2959"},"modified":"2024-03-21T11:56:43","modified_gmt":"2024-03-21T11:56:43","slug":"irse-de-practicas-a-irlanda","status":"publish","type":"post","link":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/","title":{"rendered":"Irse de pr\u00e1cticas a Irlanda"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Irlanda es uno de los principales destinos elegidos por los estudiantes ya sea para estudiar en el extranjero, mejorar su nivel de ingl\u00e9s o realizar pr\u00e1cticas<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El idioma, la diversidad cultural y las oportunidades de trabajo son varias de las razones que atraen a los j\u00f3venes estudiantes a Irlanda.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las ofertas de pr\u00e1cticas y de trabajo aumentan cada a\u00f1o en el pa\u00eds, lo que supone una gran oportunidad a tener en cuenta a la hora de buscar unas pr\u00e1cticas en el extranjero.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">tranjero.\u00a0<\/span><\/p>\n<h2><b>Las ventajas de realizar las pr\u00e1cticas en Irlanda<\/b><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Destino ideal para mejorar el nivel de ingl\u00e9s y descubrir una gran diversidad cultural\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">uno de los pa\u00edses europeos con un fuerte crecimiento econ\u00f3mico, que ofrece muchas oportunidades de trabajo interesantes para los j\u00f3venes estudiantes\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Puedes beneficiarte de la beca Erasmus+ para financiar tu estancia completa en Irlanda durante tus pr\u00e1cticas o tus estudios.<\/span><\/li>\n<\/ul>\n<h2><b>\u00bfC\u00f3mo encontrar tus pr\u00e1cticas en Irlanda?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Existen varias plataformas y fuentes que te ayudar\u00e1n a encontrar tus pr\u00e1cticas en Irlanda:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">jobs.ie : c\u2019est un des plus grandes plateformes pour trouver des offres d\u2019emploi et de stage en Irlande.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">goabroad.com : un site qui r\u00e9pertorie des stages et programmes d\u2019\u00e9changes pour apprendre ou enseigner une langue \u00e0 l\u2019\u00e9tranger.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">xperience.ie : une plateforme qui r\u00e9pertorie des stages exclusivement en Irlande par ville, secteur et r\u00e9mun\u00e9ration.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">irishjobs.ie : un site qui r\u00e9pertorie des offres d\u2019emploi et de stage en Irlande exclusivement.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">jobs.ie: es una de las mayores plataformas para encontrar trabajo y pr\u00e1cticas en Irlanda.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">goabroad.com: un sitio web que enumera las pr\u00e1cticas y los programas de intercambio para aprender o ense\u00f1ar un idioma en el extranjero.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">xperience.ie : una plataforma que enumera las pr\u00e1cticas exclusivamente en Irlanda por ciudad, sector y salario.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">irishjobs.ie : un sitio web que recoge las ofertas de empleo y pr\u00e1cticas en Irlanda exclusivamente.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n es posible encontrar pr\u00e1cticas en Irlanda a trav\u00e9s de agencias de empleo, que ofrecen pr\u00e1cticas en todos los campos al estar asociadas con empresas en varias ciudades de Irlanda.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mobi Trainee te ayudar\u00e1 en tu b\u00fasqueda de pr\u00e1cticas en Irlanda a trav\u00e9s de un coaching personalizado en funci\u00f3n de tus habilidades, experiencia y deseos. Ponerse en contacto con ellos es muy sencillo, s\u00f3lo tienes que enviar tu CV a <\/span><a href=\"mailto:contact@mobitrainee.com\"><span style=\"font-weight: 400;\">contact@mobitrainee.com<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, tambi\u00e9n es importante ponerse en contacto con las universidades, ya que muchas empresas irlandesas contratan directamente en las escuelas y universidades en lugar de hacerlo a trav\u00e9s de plataformas online.<\/span><\/p>\n<h2><b>\u00bfCu\u00e1les son las ciudades m\u00e1s atractivas de Irlanda?\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Irlanda es un pa\u00eds muy din\u00e1mico que acoge a muchos estudiantes extranjeros cada a\u00f1o. Para hacer pr\u00e1cticas en Irlanda, los estudiantes pueden solicitarlas en <\/span><b>Dubl\u00edn, Galway, Longford, Leitrim, Kerry, Sligo y Cork<\/b><span style=\"font-weight: 400;\">, que presentan interesantes oportunidades debido a la din\u00e1mica econ\u00f3mica de todas estas ciudades<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En todas estas ciudades hay una gran concentraci\u00f3n urbana, lo que las convierte en un lugar ideal para reuniones, eventos y salidas.\u00a0<\/span><\/p>\n<p><b>\u00bfCu\u00e1l es la legislaci\u00f3n de las pr\u00e1cticas en Irlanda?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El gobierno irland\u00e9s ha decidido regular el estatus de trabajador en pr\u00e1cticas para regular las condiciones laborales de los becarios en el territorio. Los trabajadores en pr\u00e1cticas tienen un salario m\u00ednimo desde julio de 2011 que es el siguiente:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En el primer tercio del periodo de pr\u00e1cticas el becario cobra 6,49 euros por hora.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En el segundo tercio la remuneraci\u00f3n es de 6,92 euros<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En el tercero, la remuneraci\u00f3n es de 7,79 euros.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Nota: cada uno de estos periodos debe tener una duraci\u00f3n m\u00ednima de un mes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para beneficiar del estatus de \u2018\u2019trabajador de pr\u00e1cticas\u2019\u2019 el estudiante debe cumplir ciertos criterios:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">el becario debe estar presente durante las pr\u00e1cticas\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">el tutor debe orientar al alumno hacia misiones espec\u00edficas que habr\u00e1 establecido de antemano\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la evaluaci\u00f3n debe realizarse al final de las pr\u00e1cticas\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">se debe entregar un certificado al final de las pr\u00e1cticas<\/span><\/li>\n<\/ul>\n<h2><b>\u00bfCu\u00e1les son los pasos a seguir para realizar unas pr\u00e1cticas en Irlanda?\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los estudiantes franceses no necesitan un visado ni un permiso de trabajo\/residencia para realizar sus pr\u00e1cticas en Irlanda.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, para las pr\u00e1cticas que superan los tres meses de duraci\u00f3n, los estudiantes deben solicitar un permiso de residencia en la oficina de polic\u00eda de la ciudad donde realizan las pr\u00e1cticas. Para obtener este permiso, el estudiante tendr\u00e1 que rellenar formularios y aportar documentos justificativos. Para m\u00e1s informaci\u00f3n, visite las p\u00e1ginas web oficiales del gobierno irland\u00e9s Permiso General de Trabajo y Permisos de Trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para unas pr\u00e1cticas en el extranjero, los elementos esenciales que se deben tener en cuenta en un convenio de pr\u00e1cticas son:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la duraci\u00f3n de las pr\u00e1cticas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">las condiciones y la remuneraci\u00f3n<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les misiones y los objetivos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">los seguros contratados<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Es imprescindible que el acuerdo sea firmado por las tres partes: el centro educativo del estudiante, el becario y la instituci\u00f3n de acogida (empresa, asociaci\u00f3n u otra).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No olvides que puedes beneficiarte de una beca Erasmus+ para financiar tu estancia en Irlanda durante tus pr\u00e1cticas. Aqu\u00ed tienes algunos consejos sobre c\u00f3mo redactar un CV y una carta de presentaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para obtener la beca, el proceso es muy sencillo, para m\u00e1s informaci\u00f3n no dudes en consultar el art\u00edculo sobre becas de movilidad internacional. Contacta con nosotros enviando un mail a contact@mobitrainee.com.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para saber m\u00e1s sobre otros destinos:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hacer las pr\u00e1cticas en Berl\u00edn<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pr\u00e1cticas en los pa\u00edses b\u00e1lticos (Letonia, Estonia, Lituania)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los pa\u00edses escandinavos est\u00e1n de moda para las pr\u00e1cticas Erasmus<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erasmus + <\/span><span style=\"font-weight: 400;\">destinos<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Irlanda es uno de los principales destinos elegidos por los estudiantes ya sea para estudiar en el extranjero, mejorar su nivel de ingl\u00e9s o realizar pr\u00e1cticas El idioma, la diversidad cultural y las oportunidades de trabajo son varias de las razones que atraen a los j\u00f3venes estudiantes a Irlanda.\u00a0 Las ofertas de pr\u00e1cticas y de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-2959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erasmus-es","category-55","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Irse de pr\u00e1cticas a Irlanda - Mobi Trainee<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irse de pr\u00e1cticas a Irlanda\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobi Trainee\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T09:26:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T11:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandra seknagi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandra seknagi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/\"},\"author\":{\"name\":\"sandra seknagi\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/#\\\/schema\\\/person\\\/24668b0791f3a96b831cf177900f1287\"},\"headline\":\"Irse de pr\u00e1cticas a Irlanda\",\"datePublished\":\"2021-04-30T09:26:00+00:00\",\"dateModified\":\"2024-03-21T11:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/\"},\"wordCount\":997,\"image\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mobitrainee.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/stage-Irlande-erasmus.jpg\",\"articleSection\":[\"Erasmus +\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/\",\"url\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/\",\"name\":\"Irse de pr\u00e1cticas a Irlanda - Mobi Trainee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mobitrainee.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/stage-Irlande-erasmus.jpg\",\"datePublished\":\"2021-04-30T09:26:00+00:00\",\"dateModified\":\"2024-03-21T11:56:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/#\\\/schema\\\/person\\\/24668b0791f3a96b831cf177900f1287\"},\"description\":\"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mobitrainee.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/stage-Irlande-erasmus.jpg\",\"contentUrl\":\"https:\\\/\\\/mobitrainee.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/stage-Irlande-erasmus.jpg\",\"width\":1600,\"height\":1068,\"caption\":\"stage Irlande erasmus +\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/irse-de-practicas-a-irlanda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irse de pr\u00e1cticas a Irlanda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/#website\",\"url\":\"https:\\\/\\\/mobitrainee.com\\\/\",\"name\":\"Mobi Trainee\",\"description\":\"Experts en mobilit\u00e9s en stage Erasmus+\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mobitrainee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mobitrainee.com\\\/#\\\/schema\\\/person\\\/24668b0791f3a96b831cf177900f1287\",\"name\":\"sandra seknagi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g\",\"caption\":\"sandra seknagi\"},\"url\":\"https:\\\/\\\/mobitrainee.com\\\/es\\\/author\\\/sandra-seknagi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Irse de pr\u00e1cticas a Irlanda - Mobi Trainee","description":"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/","og_locale":"es_ES","og_type":"article","og_title":"Irse de pr\u00e1cticas a Irlanda","og_description":"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.","og_url":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/","og_site_name":"Mobi Trainee","article_published_time":"2021-04-30T09:26:00+00:00","article_modified_time":"2024-03-21T11:56:43+00:00","og_image":[{"width":1600,"height":1068,"url":"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg","type":"image\/jpeg"}],"author":"sandra seknagi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sandra seknagi","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#article","isPartOf":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/"},"author":{"name":"sandra seknagi","@id":"https:\/\/mobitrainee.com\/#\/schema\/person\/24668b0791f3a96b831cf177900f1287"},"headline":"Irse de pr\u00e1cticas a Irlanda","datePublished":"2021-04-30T09:26:00+00:00","dateModified":"2024-03-21T11:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/"},"wordCount":997,"image":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#primaryimage"},"thumbnailUrl":"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg","articleSection":["Erasmus +"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/","url":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/","name":"Irse de pr\u00e1cticas a Irlanda - Mobi Trainee","isPartOf":{"@id":"https:\/\/mobitrainee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#primaryimage"},"image":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#primaryimage"},"thumbnailUrl":"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg","datePublished":"2021-04-30T09:26:00+00:00","dateModified":"2024-03-21T11:56:43+00:00","author":{"@id":"https:\/\/mobitrainee.com\/#\/schema\/person\/24668b0791f3a96b831cf177900f1287"},"description":"Descubre c\u00f3mo irse de pr\u00e1cticas a Irlanda con Mobitrainee. Obt\u00e9n informaci\u00f3n sobre oportunidades de trabajo, requisitos de visado y experiencias de aprendizaje en este pa\u00eds europeo vibrante.","breadcrumb":{"@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#primaryimage","url":"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg","contentUrl":"https:\/\/mobitrainee.com\/wp-content\/uploads\/2021\/04\/stage-Irlande-erasmus.jpg","width":1600,"height":1068,"caption":"stage Irlande erasmus +"},{"@type":"BreadcrumbList","@id":"https:\/\/mobitrainee.com\/es\/irse-de-practicas-a-irlanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mobitrainee.com\/es\/"},{"@type":"ListItem","position":2,"name":"Irse de pr\u00e1cticas a Irlanda"}]},{"@type":"WebSite","@id":"https:\/\/mobitrainee.com\/#website","url":"https:\/\/mobitrainee.com\/","name":"Mobi Trainee","description":"Experts en mobilit\u00e9s en stage Erasmus+","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobitrainee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mobitrainee.com\/#\/schema\/person\/24668b0791f3a96b831cf177900f1287","name":"sandra seknagi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ea8de7868a92bde41edda38ed5a7a48fb9bad62b08fa55ce0b5339c3aa29084?s=96&d=mm&r=g","caption":"sandra seknagi"},"url":"https:\/\/mobitrainee.com\/es\/author\/sandra-seknagi\/"}]}},"_links":{"self":[{"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/posts\/2959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/comments?post=2959"}],"version-history":[{"count":1,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/posts\/2959\/revisions"}],"predecessor-version":[{"id":2960,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/posts\/2959\/revisions\/2960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/media\/2942"}],"wp:attachment":[{"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/media?parent=2959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/categories?post=2959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobitrainee.com\/es\/wp-json\/wp\/v2\/tags?post=2959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}